{"id":55,"date":"2026-02-07T05:27:47","date_gmt":"2026-02-07T05:27:47","guid":{"rendered":"https:\/\/damnoensaduak.com\/?page_id=55"},"modified":"2026-02-07T05:27:48","modified_gmt":"2026-02-07T05:27:48","slug":"impronta","status":"publish","type":"page","link":"https:\/\/damnoensaduak.com\/it\/imprint\/","title":{"rendered":"Informazioni legali"},"content":{"rendered":"<p>Patrick K\u00fchne<br>Kolpingstr. 12<br>04416 Markkleeberg<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Contattateci<\/h2>\n\n\n\n<p>E-mail: patrick@101places.de.de<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">ID imposta sulle vendite<\/h2>\n\n\n\n<p>Numero di identificazione dell'imposta sulle vendite ai sensi del \u00a7 27 a della legge sull'imposta sulle vendite:<br>DE251359457<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Risoluzione delle controversie dei consumatori<\/h2>\n\n\n\n<p>Non siamo disposti o obbligati a partecipare a procedure di risoluzione delle controversie davanti a un collegio arbitrale dei consumatori.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Patrick K\u00fchneKolpingstr. 1204416 Markkleeberg Contatto Email: patrick@101places.de.de Partita IVA Numero di identificazione IVA ai sensi del \u00a7 27 a Umsatzsteuergesetz:DE251359457 Risoluzione delle controversie dei consumatori Non siamo disposti o obbligati a partecipare a procedure di risoluzione delle controversie davanti a un collegio arbitrale dei consumatori.<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-55","page","type-page","status-publish"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/damnoensaduak.com\/it\/wp-json\/wp\/v2\/pages\/55","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/damnoensaduak.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/damnoensaduak.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/damnoensaduak.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/damnoensaduak.com\/it\/wp-json\/wp\/v2\/comments?post=55"}],"version-history":[{"count":1,"href":"https:\/\/damnoensaduak.com\/it\/wp-json\/wp\/v2\/pages\/55\/revisions"}],"predecessor-version":[{"id":56,"href":"https:\/\/damnoensaduak.com\/it\/wp-json\/wp\/v2\/pages\/55\/revisions\/56"}],"wp:attachment":[{"href":"https:\/\/damnoensaduak.com\/it\/wp-json\/wp\/v2\/media?parent=55"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}